{"id":1504,"count":9,"description":"","link":"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/","name":"Destructoras Despach","slug":"destructoras-despach","taxonomy":"product_cat","parent":1422,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Destructoras de papel para despachos y oficinas.<\/title>\n<meta name=\"description\" content=\"Las Destructoras de despacho son adecuadas para grupos de dos a cinco personas en una oficina o centro de trabajo. Varios modelos de destructoras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Destructoras de papel para despachos y oficinas.\" \/>\n<meta property=\"og:description\" content=\"Las Destructoras de despacho son adecuadas para grupos de dos a cinco personas en una oficina o centro de trabajo. Varios modelos de destructoras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/\" \/>\n<meta property=\"og:site_name\" content=\"neodal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/neodal.es\\\/ca\\\/categoria-producte\\\/destructoras-de-paper\\\/destructoras-despach\\\/\",\"url\":\"https:\\\/\\\/neodal.es\\\/ca\\\/categoria-producte\\\/destructoras-de-paper\\\/destructoras-despach\\\/\",\"name\":\"Destructoras de papel para despachos y oficinas.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/neodal.es\\\/ca\\\/#website\"},\"description\":\"Las Destructoras de despacho son adecuadas para grupos de dos a cinco personas en una oficina o centro de trabajo. Varios modelos de destructoras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/neodal.es\\\/ca\\\/categoria-producte\\\/destructoras-de-paper\\\/destructoras-despach\\\/#breadcrumb\"},\"inLanguage\":\"ca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/neodal.es\\\/ca\\\/categoria-producte\\\/destructoras-de-paper\\\/destructoras-despach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/neodal.es\\\/ca\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Destructoras de Paper\",\"item\":\"https:\\\/\\\/neodal.es\\\/ca\\\/categoria-producte\\\/destructoras-de-paper\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Destructoras Despach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/neodal.es\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/neodal.es\\\/ca\\\/\",\"name\":\"neodal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/neodal.es\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Destructoras de papel para despachos y oficinas.","description":"Las Destructoras de despacho son adecuadas para grupos de dos a cinco personas en una oficina o centro de trabajo. Varios modelos de destructoras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/","og_locale":"ca_ES","og_type":"article","og_title":"Destructoras de papel para despachos y oficinas.","og_description":"Las Destructoras de despacho son adecuadas para grupos de dos a cinco personas en una oficina o centro de trabajo. Varios modelos de destructoras.","og_url":"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/","og_site_name":"neodal","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/","url":"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/","name":"Destructoras de papel para despachos y oficinas.","isPartOf":{"@id":"https:\/\/neodal.es\/ca\/#website"},"description":"Las Destructoras de despacho son adecuadas para grupos de dos a cinco personas en una oficina o centro de trabajo. Varios modelos de destructoras.","breadcrumb":{"@id":"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/#breadcrumb"},"inLanguage":"ca"},{"@type":"BreadcrumbList","@id":"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/destructoras-despach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/neodal.es\/ca\/home\/"},{"@type":"ListItem","position":2,"name":"Destructoras de Paper","item":"https:\/\/neodal.es\/ca\/categoria-producte\/destructoras-de-paper\/"},{"@type":"ListItem","position":3,"name":"Destructoras Despach"}]},{"@type":"WebSite","@id":"https:\/\/neodal.es\/ca\/#website","url":"https:\/\/neodal.es\/ca\/","name":"neodal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/neodal.es\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"}]}},"_links":{"self":[{"href":"https:\/\/neodal.es\/ca\/wp-json\/wp\/v2\/product_cat\/1504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neodal.es\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/neodal.es\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/neodal.es\/ca\/wp-json\/wp\/v2\/product_cat\/1422"}],"wp:post_type":[{"href":"https:\/\/neodal.es\/ca\/wp-json\/wp\/v2\/product?product_cat=1504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}